{"id":375,"date":"2012-12-26T17:44:33","date_gmt":"2012-12-26T20:44:33","guid":{"rendered":"http:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg"},"modified":"2012-12-26T17:44:33","modified_gmt":"2012-12-26T20:44:33","slug":"2009-01-16_0360282-subscriber-false-marketing-false-newsletter-false-regysnewsletter-true-microtransactions-false","status":"inherit","type":"attachment","link":"https:\/\/www.01argentina.com\/travel\/amazing-pictures-and-travel-information-of-antarctica-argentina\/2009-01-16_0360282-subscriber-false-marketing-false-newsletter-false-regysnewsletter-true-microtransactions-false\/","title":{"rendered":""},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"class_list":["post-375","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>-<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"-\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@01argentina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/a2.jpg\",\"url\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/a2.jpg\",\"name\":\"-\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/#website\"},\"datePublished\":\"2012-12-26T20:44:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/a2.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/a2.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/a2.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amazing pictures and travel information of Antarctica Argentina\",\"item\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/amazing-pictures-and-travel-information-of-antarctica-argentina\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/#website\",\"url\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/\",\"name\":\"\",\"description\":\"Travel to Argentina\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"-","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg","twitter_card":"summary_large_image","twitter_title":"-","twitter_image":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg","twitter_site":"@01argentina","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg","url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg","name":"-","isPartOf":{"@id":"https:\/\/www.01argentina.com\/travel\/#website"},"datePublished":"2012-12-26T20:44:33+00:00","breadcrumb":{"@id":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.01argentina.com\/travel\/"},{"@type":"ListItem","position":2,"name":"Amazing pictures and travel information of Antarctica Argentina","item":"https:\/\/www.01argentina.com\/travel\/amazing-pictures-and-travel-information-of-antarctica-argentina\/"}]},{"@type":"WebSite","@id":"https:\/\/www.01argentina.com\/travel\/#website","url":"https:\/\/www.01argentina.com\/travel\/","name":"","description":"Travel to Argentina","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.01argentina.com\/travel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_shortlink":"https:\/\/wp.me\/a2DFrg-63","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2-300x225.jpg 300w, https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"375\" data-permalink=\"https:\/\/www.01argentina.com\/travel\/amazing-pictures-and-travel-information-of-antarctica-argentina\/2009-01-16_0360282-subscriber-false-marketing-false-newsletter-false-regysnewsletter-true-microtransactions-false\/\" data-orig-file=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg\" data-orig-size=\"600,450\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;USER ID: 117456&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;This very amazing shaped iceberg was shot in Plenau Bay, Antarctica.&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;2009-01-16_0360282   Subscriber-false   Marketing-false   Newsletter-false   RegYSNewsletter-true  MicroTransactions-false&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":450,"file":"2012\/12\/a2.jpg","sizes":{"thumbnail":{"file":"a2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2-150x150.jpg"},"medium":{"file":"a2-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2-300x225.jpg"},"post-thumbnail":{"file":"a2-600x198.jpg","width":600,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2-600x198.jpg"},"full":{"file":"a2.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg"}},"image_meta":{"aperture":0,"credit":"USER ID: 117456","camera":"","caption":"This very amazing shaped iceberg was shot in Plenau Bay, Antarctica.","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"2009-01-16_0360282   Subscriber-false   Marketing-false   Newsletter-false   RegYSNewsletter-true  MicroTransactions-false"}},"post":372,"source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2012\/12\/a2.jpg","_links":{"self":[{"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/media\/375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/comments?post=375"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":372,"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/posts\/372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}