{"id":1274,"date":"2016-08-11T16:23:10","date_gmt":"2016-08-11T19:23:10","guid":{"rendered":"http:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg"},"modified":"2016-08-11T16:23:10","modified_gmt":"2016-08-11T19:23:10","slug":"iguazufalls04","status":"inherit","type":"attachment","link":"https:\/\/www.01argentina.com\/travel\/iguazu-falls-tourism\/iguazufalls04\/","title":{"rendered":"iguazufalls04"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-1274","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>iguazufalls04 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"iguazufalls04 -\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@01argentina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/iguazufalls04.jpg\",\"url\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/iguazufalls04.jpg\",\"name\":\"iguazufalls04 -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/#website\"},\"datePublished\":\"2016-08-11T19:23:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/iguazufalls04.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/iguazufalls04.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/iguazufalls04.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iguazu falls tourism\",\"item\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/iguazu-falls-tourism\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"iguazufalls04\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/#website\",\"url\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/\",\"name\":\"\",\"description\":\"Travel to Argentina\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.01argentina.com\\\/travel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"iguazufalls04 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg","twitter_card":"summary_large_image","twitter_title":"iguazufalls04 -","twitter_image":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg","twitter_site":"@01argentina","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg","url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg","name":"iguazufalls04 -","isPartOf":{"@id":"https:\/\/www.01argentina.com\/travel\/#website"},"datePublished":"2016-08-11T19:23:10+00:00","breadcrumb":{"@id":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.01argentina.com\/travel\/"},{"@type":"ListItem","position":2,"name":"Iguazu falls tourism","item":"https:\/\/www.01argentina.com\/travel\/iguazu-falls-tourism\/"},{"@type":"ListItem","position":3,"name":"iguazufalls04"}]},{"@type":"WebSite","@id":"https:\/\/www.01argentina.com\/travel\/#website","url":"https:\/\/www.01argentina.com\/travel\/","name":"","description":"Travel to Argentina","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.01argentina.com\/travel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_shortlink":"https:\/\/wp.me\/a2DFrg-ky","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"184\" src=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04-300x184.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04-300x184.jpg 300w, https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"1274\" data-permalink=\"https:\/\/www.01argentina.com\/travel\/iguazu-falls-tourism\/iguazufalls04\/\" data-orig-file=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg\" data-orig-size=\"700,429\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"iguazufalls04\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":429,"file":"2016\/08\/iguazufalls04.jpg","sizes":{"thumbnail":{"file":"iguazufalls04-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04-150x150.jpg"},"medium":{"file":"iguazufalls04-300x184.jpg","width":300,"height":184,"mime_type":"image\/jpeg","source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04-300x184.jpg"},"wptouch-new-thumbnail":{"file":"iguazufalls04-144x144.jpg","width":144,"height":144,"mime_type":"image\/jpeg","source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04-144x144.jpg"},"post-thumbnail":{"file":"iguazufalls04-700x198.jpg","width":700,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04-700x198.jpg"},"full":{"file":"iguazufalls04.jpg","width":700,"height":429,"mime_type":"image\/jpeg","source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1270,"source_url":"https:\/\/www.01argentina.com\/travel\/wp-content\/uploads\/2016\/08\/iguazufalls04.jpg","_links":{"self":[{"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/media\/1274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/comments?post=1274"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1270,"href":"https:\/\/www.01argentina.com\/travel\/wp-json\/wp\/v2\/posts\/1270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}